{"id":6412,"date":"2019-11-06T12:27:51","date_gmt":"2019-11-06T17:27:51","guid":{"rendered":"http:\/\/convention.cpa.ca\/scientific-program\/presentation-types-2\/"},"modified":"2025-11-28T10:29:37","modified_gmt":"2025-11-28T15:29:37","slug":"presentation-types","status":"publish","type":"page","link":"https:\/\/convention.cpa.ca\/fr\/scientific-program\/presentation-types\/","title":{"rendered":"Types de pr\u00e9sentations du programme scientifique du congr\u00e8s national annuel de la SCP"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<h1>TYPES DE PR\u00c9SENTATION AU CONGR\u00c8S DE 2026<\/h1>\n<p>Le congr\u00e8s annuel de la SCP de 2026 aura \u00e0 son programme une multitude de pr\u00e9sentations de divers types. Il s\u2019agit notamment de :<\/p>\n<ul style=\"margin-left: 20px;\">\n<li><a href=\"#workshops\"><strong>Ateliers<\/strong><\/a> (de dur\u00e9e variable et d\u2019admissibilit\u00e9 variable aux cr\u00e9dits de formation continue, y compris des ateliers de 6 heures, de 3 heures et de 85 minutes)<\/li>\n<li><a href=\"#spokenindividual\"><strong>Communications orales individuelles<\/strong><\/a> (de dur\u00e9e variable, y compris des pr\u00e9sentations \u00e9clair de 5\u00a0minutes, des pr\u00e9sentations orales de 12\u00a0minutes, des r\u00e9unions d\u2019\u00e9change de 25\u00a0minutes et des s\u00e9ances th\u00e9oriques de 25\u00a0minutes)<\/li>\n<li><a href=\"#spokengroup\"><strong>Communications orales de groupe<\/strong><\/a> (de dur\u00e9e variable, y compris des discussions en groupe de 55\u00a0minutes et des symposiums de 55\u00a0minutes)<\/li>\n<li><a href=\"#posters\"><strong>Affiches<\/strong><\/a> (affiches papier)<\/li>\n<\/ul>\n<p>Vous trouverez ci-dessous de plus amples renseignements sur chacun de ces types de pr\u00e9sentation, y compris la description et les exigences relatives \u00e0 la proposition de communications de chaque type de pr\u00e9sentation.<\/p>\n<div style=\"margin-left: 50px;\">\n<hr style=\"margin-left: -50px;\" \/>\n<p>&nbsp;<\/p>\n<h3 style=\"margin-left: -50px;\">ATELIERS<\/h3>\n<p>Le congr\u00e8s de la SCP de 20256 proposera trois types d\u2019ateliers :<\/p>\n<ul style=\"margin-left: 20px;\">\n<li>Ateliers pr\u00e9congr\u00e8s de perfectionnement professionnel de 6 heures\/6 cr\u00e9dits de formation continue<\/li>\n<li>Ateliers pr\u00e9congr\u00e8s de perfectionnement professionnel de 3 heures\/3 cr\u00e9dits de formation continue<\/li>\n<li>Ateliers de 85\u00a0minutes (certains donneront droit \u00e0 des cr\u00e9dits)<\/li>\n<\/ul>\n<h4 style=\"margin-left: -20px;\">Ateliers pr\u00e9congr\u00e8s de perfectionnement professionnel de 3+ heures\/3 cr\u00e9dits de formation continue et de 6+ heures\/6 cr\u00e9dits de formation continue<\/h4>\n<p>\u00c0 partir de cette ann\u00e9e, la SCP n\u2019acceptera plus de propositions d\u2019ateliers pr\u00e9congr\u00e8s de perfectionnement professionnel. En revanche, notre \u00e9quipe recherchera activement des intervenants et des th\u00e8mes pour la journ\u00e9e de formation pr\u00e9congr\u00e8s. Nous esp\u00e9rons qu\u2019il en r\u00e9sultera des th\u00e9matiques plus en phase avec les besoins et les int\u00e9r\u00eats des membres et des participants.<\/p>\n<p>Pour plus d\u2019informations, veuillez consulter notre page <a href=\"https:\/\/convention.cpa.ca\/fr\/workshops\/pre-convention-program\/\">Ateliers de perfectionnement professionnel pr\u00e9congr\u00e8s<\/a>.<\/p>\n<h4 style=\"margin-left: -20px;\">Atelier (85\u00a0minutes)<\/h4>\n<p>Les ateliers, d\u2019une dur\u00e9e de 85\u00a0minutes, sont pr\u00e9sent\u00e9s par une personne ou un groupe dont l\u2019exp\u00e9rience et l\u2019expertise du sujet trait\u00e9 sont largement reconnues.<\/p>\n<p>Les ateliers sont cens\u00e9s avoir une composante pratique et exp\u00e9rientielle et\/ou comprendre des d\u00e9monstrations; il s\u2019agit d\u2019activit\u00e9s participatives, o\u00f9 les d\u00e9l\u00e9gu\u00e9s prennent part \u00e0 la discussion et interagissent entre eux. Chaque atelier doit faire en sorte que les participants acqui\u00e8rent, au terme de l\u2019activit\u00e9, au moins trois comp\u00e9tences, techniques et\/ou outils nouveaux et concrets (c.-\u00e0-d., r\u00e9sultats d\u2019apprentissage). Ainsi, un bon atelier est novateur, interactif, inclusif, int\u00e9gr\u00e9 et instructif; il interpelle les participants et est bien organis\u00e9, et il offre, \u00e0 la fois aux psychologues exp\u00e9riment\u00e9s et aux psychologues en d\u00e9but de carri\u00e8re, la possibilit\u00e9 de poursuivre leur perfectionnement professionnel.<\/p>\n<p>Des cr\u00e9dits de formation continue peuvent \u00eatre accord\u00e9s, le cas \u00e9ch\u00e9ant. La conversion en cours de perfectionnement professionnel continu pourrait \u00e9galement se faire.<\/p>\n<p>Les intervenants accept\u00e9s seront tenus de pr\u00e9senter leur atelier en personne et sur place.<\/p>\n<hr style=\"margin-left: -50px;\" \/>\n<p>&nbsp;<\/p>\n<h3 style=\"margin-left: -50px;\">COMMUNICATIONS ORALES INDIVIDUELLES<\/h3>\n<h4 style=\"margin-left: -20px;\">Pr\u00e9sentations \u00e9clair (5\u00a0minutes)<\/h4>\n<p>La pr\u00e9sentation \u00e9clair est un type de pr\u00e9sentation qui permet de transmettre de l\u2019information oralement, \u00e0 l\u2019aide de supports visuels et de fa\u00e7on succincte, de susciter de l\u2019int\u00e9r\u00eat \u00e0 l\u2019\u00e9gard d\u2019un projet ou d\u2019un programme et de favoriser le r\u00e9seautage entre les d\u00e9l\u00e9gu\u00e9s. Ce format est recommand\u00e9 aux participants qui souhaitent pr\u00e9senter leurs recherches sous la forme d\u2019un expos\u00e9 plut\u00f4t que d\u2019une affiche.<\/p>\n<p>Les pr\u00e9sentations \u00e9clair ne peuvent comporter plus de trois diapositives et seront regroup\u00e9es en s\u00e9ances. Pour \u00eatre efficace, une pr\u00e9sentation \u00e9clair doit se concentrer sur l\u2019essentiel et \u00eatre livr\u00e9e de mani\u00e8re stimulante, tout en suscitant la r\u00e9flexion.<\/p>\n<p>Les propositions de pr\u00e9sentation \u00e9clair doivent comporter les renseignements suivants\u00a0: justification, aper\u00e7u de la m\u00e9thodologie, r\u00e9sum\u00e9 des analyses ou des \u00e9valuations r\u00e9alis\u00e9es, conclusions qui d\u00e9coulent des r\u00e9sultats ou de l\u2019\u00e9valuation et aper\u00e7u des mesures, des recommandations ou des r\u00e9percussions.<\/p>\n<p>D&rsquo;ici le 3 juin, tous les intervenants accept\u00e9s doivent se pr\u00e9senter leur pr\u00e9sentation \u00e9clair (diapositives non accompagn\u00e9es d&rsquo;une narration hors champ) au service des congr\u00e8s de la SCP.<\/p>\n<p>Les individus peuvent \u00e9galement choisir de t\u00e9l\u00e9charger une version enregistr\u00e9e en voix off de leur pr\u00e9sentation \u00e9clair sur l&rsquo;application mobile virtuelle du SCP pour une promotion par le service de communication du SCP au cours de l&rsquo;\u00e9t\u00e9.<\/p>\n<h4 style=\"margin-left: -20px;\">Communications orales de 12\u00a0minutes (12 minutes)<\/h4>\n<p>La communication orale de 12\u00a0minutes vise \u00e0 faire un rapport d\u00e9taill\u00e9 sur une s\u00e9rie d\u2019\u00e9tudes empiriques (plus de deux), ou un programme ou une intervention complexe.<\/p>\n<p>Les communications orales de 12\u00a0minutes sont structur\u00e9es comme suit\u00a0: 10\u00a0minutes pour la pr\u00e9sentation et trois minutes r\u00e9serv\u00e9es aux questions. Ce type de communication est r\u00e9serv\u00e9 \u00e0 l\u2019\u00e9change d\u2019informations sur une s\u00e9rie complexe d\u2019\u00e9tudes ou un programme ou une intervention compliqu\u00e9s.<\/p>\n<p>Les propositions de communication orale de 12\u00a0minutes doivent comporter les renseignements suivants\u00a0: le contexte empirique et th\u00e9orique et la justification des \u00e9tudes ou du programme\/politique ou de l\u2019intervention; la m\u00e9thodologie g\u00e9n\u00e9rale des \u00e9tudes ou l\u2019approche employ\u00e9e pour concevoir le programme\/politique ou l\u2019intervention; un r\u00e9sum\u00e9 des analyses, des r\u00e9sultats et des conclusions; un aper\u00e7u des mesures, des recommandations ou des r\u00e9percussions engendr\u00e9es, qui seront mises en \u0153uvre ou \u00e9valu\u00e9es.<\/p>\n<p>Des efforts sont faits pour regrouper les propositions de communication orale de 12 minutes en sessions organis\u00e9es autour d&rsquo;un th\u00e8me ou d&rsquo;un sujet sp\u00e9cifique.<\/p>\n<h4 style=\"margin-left: -20px;\">S\u00e9ances th\u00e9oriques (25 minutes)<\/h4>\n<p>Les s\u00e9ances th\u00e9oriques servent \u00e0 examiner une ou plusieurs perspectives\/m\u00e9thodes\/analyses th\u00e9oriques ou \u00e0 faire la synth\u00e8se de perspectives\/m\u00e9thodes\/analyses th\u00e9oriques. Ce type de communication ne sert pas \u00e0 pr\u00e9senter de nouvelles recherches empiriques. L\u2019intervenant qui pr\u00e9sente une s\u00e9ance th\u00e9orique est habituellement un expert chevronn\u00e9 du sujet trait\u00e9; les propositions soumises par un d\u00e9butant dans le domaine ne seront pas accept\u00e9es. Il peut arriver que trois pr\u00e9sentations soient regroup\u00e9es en une seule s\u00e9ance, le mod\u00e9rateur \u00e9tant charg\u00e9 de faire respecter l\u2019horaire.<\/p>\n<h4 style=\"margin-left: -20px;\">R\u00e9unions d\u2019\u00e9change (25 minutes)<\/h4>\n<p>Les r\u00e9unions d\u2019\u00e9change visent \u00e0 \u00e9changer, explorer et susciter des id\u00e9es et des r\u00e9flexions sur un sujet\/th\u00e8me\/cas, un programme ou une intervention; elles servent \u00e9galement \u00e0 lancer des id\u00e9es sur des m\u00e9thodes novatrices en mati\u00e8re de recherche, de pratique, d\u2019enseignement et\/ou de politiques dans un format de \u00ab conversation \u00bb sans AV par opposition \u00e0 un format de pr\u00e9sentation formel avec AV.<\/p>\n<p>Chaque r\u00e9union d\u2019\u00e9change est propos\u00e9e par un animateur, qui doit fournir un r\u00e9sum\u00e9 succinct, mais clair (15\u00a0minutes maximum) des principaux points, id\u00e9es, approches, interventions, etc. \u00e0 d\u00e9battre et \u00e0 explorer. En outre, l\u2019animateur doit inciter les participants \u00e0 \u00e9changer et \u00e0 interagir les uns avec les autres, et \u00e0 se centrer sur le sujet de la r\u00e9union (minimum 10\u00a0minutes).<\/p>\n<p>Les propositions de r\u00e9union d\u2019\u00e9change doivent comprendre les \u00e9l\u00e9ments suivants\u00a0: un \u00e9nonc\u00e9 des principales questions, id\u00e9es ou approches, interventions, etc. \u00e0 d\u00e9battre et \u00e0 explorer; un \u00e9nonc\u00e9 expliquant pourquoi ces questions, id\u00e9es, etc. sont d\u2019actualit\u00e9 et propices \u00e0 l\u2019\u00e9change d\u2019id\u00e9es; une description des m\u00e9thodes \u00e0 utiliser pour encourager les participants \u00e0 \u00e9changer, \u00e0 s\u2019int\u00e9resser au sujet du forum et \u00e0 interagir les uns avec les autres.<\/p>\n<p>Les propositions de r\u00e9union d\u2019\u00e9change dont l\u2019objectif est de pr\u00e9senter\/examiner des recherches empiriques ne seront pas retenues.<\/p>\n<p>Les r\u00e9unions d\u2019\u00e9change seront programm\u00e9es dans une salle am\u00e9nag\u00e9e en table ronde et aucun audiovisuel ne sera fourni puisqu&rsquo;il s&rsquo;agit d&rsquo;une s\u00e9ance de conversation.<\/p>\n<hr style=\"margin-left: -50px;\" \/>\n<p>&nbsp;<\/p>\n<h3 style=\"margin-left: -50px;\">COMMUNICATIONS ORALES DE GROUPE<\/h3>\n<h4 style=\"margin-left: -20px;\">Discussion en groupe (55 minutes)<\/h4>\n<p>Une discussion en groupe est une discussion portant sur un sujet pr\u00e9cis, r\u00e9unissant un groupe s\u00e9lectionn\u00e9 d\u2019experts qui partagent des points de vue diff\u00e9rents. Elle est pr\u00e9c\u00e9d\u00e9e par une br\u00e8ve introduction et laisse ensuite la parole aux experts et au public.<\/p>\n<p>Les discussions en groupe sont g\u00e9n\u00e9ralement anim\u00e9es par un \u00ab\u00a0mod\u00e9rateur\u00a0\u00bb, qui dirige le groupe d\u2019experts et le public tout au long de la discussion. Habituellement, les discussions en groupe r\u00e9unissent trois ou quatre experts en la mati\u00e8re, qui exposent des faits, donnent leur opinion et r\u00e9pondent aux questions du public, pos\u00e9es par le mod\u00e9rateur ou pr\u00e9sent\u00e9es directement par le public.<\/p>\n<p>Une discussion en groupe n\u2019est PAS\u00a0: une s\u00e9rie d\u2019expos\u00e9s pr\u00e9sent\u00e9s l\u2019un apr\u00e8s l\u2019autre, un entretien individuel avec chacun des experts ou une simple s\u00e9ance de questions et r\u00e9ponses avec le public.<\/p>\n<p>Les propositions de discussion en groupe doivent comprendre les \u00e9l\u00e9ments suivants\u00a0: un r\u00e9sum\u00e9 g\u00e9n\u00e9ral du sujet de discussion, expliquant le caract\u00e8re in\u00e9dit ou controvers\u00e9 du sujet, ou la pertinence du sujet par rapport au th\u00e8me; le nom\/affiliation\/r\u00f4le du mod\u00e9rateur et une mention de ses qualifications pour animer la s\u00e9ance; les noms\/affiliations\/r\u00f4les de quatre experts au maximum et, pour chaque expert, un \u00e9nonc\u00e9 d\u00e9crivant clairement le point de vue particulier que chacun apportera \u00e0 la discussion.<\/p>\n<h4 style=\"margin-left: -20px;\">Symposium (55\u00a0minutes)<\/h4>\n<p>Un symposium est un type de pr\u00e9sentation o\u00f9 une s\u00e9rie de communications orales portant sur le sujet du symposium sont pr\u00e9sent\u00e9es. Chaque symposium devrait compter un mod\u00e9rateur\/animateur (qui prendra la parole pendant 10 minutes), un titre g\u00e9n\u00e9ral et un r\u00e9sum\u00e9, et trois communications (10 minutes chacune), chacune \u00e9tant accompagn\u00e9es d\u2019un titre et d\u2019un r\u00e9sum\u00e9. Les mod\u00e9rateurs du symposium peuvent d\u00e9cider de choisir un participant \u00e0 la discussion.<\/p>\n<p>Chaque symposium est cr\u00e9\u00e9 et propos\u00e9 par une personne, appel\u00e9e \u00ab\u00a0animateur du symposium\u00a0\u00bb (ou \u00ab\u00a0mod\u00e9rateur\u00a0\u00bb). Le mod\u00e9rateur\/animateur peut jouer son r\u00f4le de l\u2019une des trois mani\u00e8res suivantes\u00a0: animateur\/mod\u00e9rateur seulement, intervenant pr\u00e9sentant l\u2019une des communications orales, ou participant \u00e0 la discussion. Les intervenants qui participent \u00e0 un symposium peuvent venir du m\u00eame pays ou de pays diff\u00e9rents.<\/p>\n<p>Les propositions de symposium doivent comprendre les \u00e9l\u00e9ments suivants\u00a0:<\/p>\n<ul style=\"margin-left: 20px;\">\n<li>un r\u00e9sum\u00e9 g\u00e9n\u00e9ral du symposium accompagn\u00e9 des renseignements suivants\u00a0: une br\u00e8ve description du sujet du symposium; un \u00e9nonc\u00e9 expliquant le caract\u00e8re in\u00e9dit ou controvers\u00e9 du sujet, ou la pertinence du sujet par rapport au th\u00e8me du congr\u00e8s; un \u00e9nonc\u00e9 expliquant clairement de quelle mani\u00e8re chaque intervenant offrira une approche\/point de vue unique sur le sujet propos\u00e9.<\/li>\n<li>pour chaque intervenant \u2013 un r\u00e9sum\u00e9, o\u00f9 figure la m\u00eame information que celle demand\u00e9e aux propositions de communication orale (contexte empirique et th\u00e9orique et justification de l\u2019\u00e9tude ou du programme\/politique ou de l\u2019intervention; m\u00e9thodologie g\u00e9n\u00e9rale de l\u2019\u00e9tude ou approche employ\u00e9e pour concevoir le programme\/politique ou l\u2019intervention; un r\u00e9sum\u00e9 de la question ou des analyses, des r\u00e9sultats et des conclusions; un aper\u00e7u des mesures, des recommandations ou des r\u00e9percussions engendr\u00e9es, ou qui seront mises en \u0153uvre ou \u00e9valu\u00e9es).<\/li>\n<\/ul>\n<p>Veuillez noter\u00a0: le mod\u00e9rateur du symposium (ou l\u2019animateur) doit stimuler la participation des intervenants et de l\u2019auditoire, et faire de la discussion en groupe une exp\u00e9rience enrichissante pour tous. Avant le congr\u00e8s et la tenue du symposium, le mod\u00e9rateur\/animateur doit organiser au moins une r\u00e9union, en personne, par t\u00e9l\u00e9phone ou par voie \u00e9lectronique, avec les intervenants. Le jour du symposium, le mod\u00e9rateur\/animateur est responsable de la gestion du temps imparti (55 minutes) et veille \u00e0 ce que le symposium commence et se termine \u00e0 l\u2019heure, et que chaque membre du groupe d\u2019intervenants dispose d\u2019un temps de parole \u00e9quitable. Le mod\u00e9rateur\/animateur s\u2019assure \u00e9galement de r\u00e9server 15\u00a0minutes pendant le symposium pour donner la parole aux membres de l\u2019auditoire et veille \u00e0 ce que la discussion se termine \u00e0 l\u2019heure pr\u00e9vue.<\/p>\n<p>Le mod\u00e9rateur doit pr\u00e9senter son symposium sur place\/en personne. <!--Au congr\u00e8s de 2023, la SCP permettra \u00e0 l\u2019<strong>un <\/strong>des intervenants qui participent aux symposiums de pr\u00e9senter le symposium de mani\u00e8re virtuelle ou \u00e0 la discr\u00e9tion de l\u2019organisateur du symposium, sous forme de pr\u00e9enregistrement. Tous les autres intervenants doivent \u00eatre sur place\/en personne.--><\/p>\n<hr style=\"margin-left: -50px;\" \/>\n<p>&nbsp;<\/p>\n<h3 style=\"margin-left: -50px;\">PR\u00c9SENTATIONS PAR AFFICHES<\/h3>\n<h4 style=\"margin-left: -20px;\">Affiches papier (55\u00a0minutes)<\/h4>\n<p>Les affiches sont des pr\u00e9sentations de recherches individuelles et ind\u00e9pendantes qui permettent une interaction et des \u00e9changes sur la recherche pr\u00e9sent\u00e9e par le chercheur avec les participants du congr\u00e8s. Les affiches (format papier) constituent la m\u00e9thode de pr\u00e9sentation de recherches empiriques la plus appropri\u00e9e et la plus efficace.<\/p>\n<p>Les affiches doivent utiliser des images et des diagrammes, mais peu de mots\/texte.<\/p>\n<p>Le titre de l\u2019affiche doit indiquer les r\u00e9sultats de l\u2019\u00e9tude (ou des \u00e9tudes) ou parler de l\u2019efficacit\u00e9 ou de l\u2019impact d\u2019une politique\/programme ou d\u2019une intervention.<\/p>\n<p>Les propositions de pr\u00e9sentation par affiches doivent comporter les renseignements suivants\u00a0: justification, aper\u00e7u de la m\u00e9thodologie, r\u00e9sum\u00e9 des analyses ou des \u00e9valuations r\u00e9alis\u00e9es, conclusions qui d\u00e9coulent des r\u00e9sultats ou de l\u2019\u00e9valuation et aper\u00e7u des mesures, des recommandations ou des r\u00e9percussions.<\/p>\n<p>Des pr\u00e9cisions sur la pr\u00e9paration des affiches seront communiqu\u00e9es lorsque la proposition sera accept\u00e9e.<\/p>\n<p>Les pr\u00e9sentations par affiches sont \u00e9galement \u00e9ligibles pour une vari\u00e9t\u00e9 de <a href=\"https:\/\/cpa.ca\/fr\/etudiants\/studentawards\/\" target=\"_blank\" rel=\"noopener\">Prix \u00e9tudiants<\/a>.<\/p>\n<hr style=\"margin-left: -50px;\" \/>\n<p>&nbsp;<\/p>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TYPES DE PR\u00c9SENTATION AU CONGR\u00c8S DE 2026 Le congr\u00e8s annuel de la SCP de 2026 aura \u00e0 son programme une multitude de pr\u00e9sentations de divers types. Il s\u2019agit notamment de : Ateliers (de dur\u00e9e variable et d\u2019admissibilit\u00e9 variable aux cr\u00e9dits de formation continue, y compris des ateliers de 6 heures, de 3 heures et de [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":2507,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"The CPA\u2019s Annual National Convention features a number of different presentation types, as per below:\r\n<p>\u00a0<\/p>\r\n<div style=\"padding-left: 20px;\">\r\n\r\n<h5>Pre-Convention Professional Development Workshops (PcPDW): Half-Day (3 CE Credits) and Full-Day (6 CE Credits)<\/h5>\r\n   <div style=\"padding-left: 20px;\">\r\nThe CPA is pleased to offer a number of half- and full-day workshops for CE credits on Wednesday May 27<sup>th<\/sup>, the day prior to the official start of the 2020 CPA Annual Convention.\r\n\r\nThe presenter of a Pre-Convention Professional Development Workshop (PcPDW) is typically a senior expert in the topic area; submissions by a novice just entering a topic area will not be considered.\r\n\r\nA PcPDW is not intended for presenting new empirical research. PcPDWs are presented by an individual or a group, and are intended to have a clearly defined practical, experiential, and\/or demonstrational component. PCPDWs are intended to be participatory events where delegates engage and interact with each other. Led by a presenter or presenters with widely acknowledged expertise and experience in the topic area, each workshop should focus on ensuring that participants leave the workshop with 3-6 tangible new skills, tools, and\/or techniques (i.e., learning outcomes). Thus, good PcPDWs are innovative, interactive, inclusive, integrative, developmental, provocative, logistically sound, and provide both novice and experienced psychologists with an opportunity to continue their professional development.\r\n\r\nThe CPA will provide a travel\/accommodation reimbursement of up to $1,000.00 per PcPDW (i.e., not per presenter) for PcPDW presenters. This funding is intended solely to reimburse eligible expenses related to presenter travel and accommodation. Additional expenses (e.g., speaker fees or honoraria) are the responsibility of the workshop organizer and\/or sponsoring Section. To inquire about sponsorship for your PcPDW, please contact the appropriate CPA Section(s) at: <a target=\"_blank\" href=\"https:\/\/cpa.ca\/sections\/\" rel=\"noopener noreferrer\">https:\/\/cpa.ca\/sections\/<\/a>\r\n\r\nThe CPA bases the registration fees for pre-convention workshops on a break-even budget, meaning that registration revenue is expected to cover the costs associated with organizing the workshop. As a result, the CPA reserves the right to cancel a workshop if it has insufficient registration to cover its costs; the decision to cancel a workshop is typically communicated to workshop organizers 6 weeks prior to the start of the CPA Convention. If a workshop organizer wishes to proceed despite having insufficient registration, all costs not covered by registration revenue will be the responsibility of the workshop organizer.\r\n\t<\/div>\r\n\r\n<h5>Conversation Session \/ Discussion Forum (25-minutes):<\/h5>\r\n   <div style=\"padding-left: 20px;\">\r\nA Conversation Session or a Discussion Forum is intended for sharing, exploring and stimulating thoughts and ideas about an issue\/topic\/case, a program or intervention, or for brainstorming alternative approaches to research, practice, education, and\/or policies; they are not intended for presenting\/discussing empirical research.\r\n\r\nEach Conversation Session \/ Discussion Forum is submitted by a leader who is expected to provide a clear but brief summary (15-minutes maximum) of the core issues, ideas or approaches, interventions, etc. to be shared and explored. In addition, the leader is expected to inspire participants into sharing and engaging with each other and with the forum topic (minimum 10-minutes).\r\n\r\nA submission for a Conversation Session \/ Discussion Forum must include the following: a statement of the critical issues, ideas or approaches, interventions, etc. to be shared and explored; a statement of why these issues, ideas, etc. are of current interest and appropriate for brainstorming; and a description of methods to be used for encouraging participants to share and engage with the forum topic and with each other.\r\n\r\n<strong><em>Note:<\/em><\/strong> No audio visual will be provided for this type of session.\u00a0 Space is limited to only 12 participants per accepted session\/forum.\r\n<\/div>\r\n\r\n<h5>GIMME-5 (5-minute Spoken Presentation)<\/h5>\r\n   <div style=\"padding-left: 20px;\">\r\nThe GIMME-5 is a method for sharing information in a spoken\/visual format in a succinct manner, and for creating interest in a project or program. A GIMME-5 can be used for presenting empirical research, or for highlighting the need for\/development of impact or evaluation of a program, policy or intervention.\r\n\r\nEach GIMME-5 is allocated a total of 5-minutes (e.g., 4-minutes for a spoken presentation and 1-minute for questions), and each is permitted a maximum of 3 slides. To be effective, a GIMME-5 presentation needs to focus on what is critical, and it needs to be delivered in a stimulating and thought-provoking manner. GIMME-5 sessions are created by including at least 8 individual GIMME-5 presentations.\r\n\r\nA submission for a GIMME-5 should include the following information: the rationale for the study\/studies or program\/policy or intervention; the method of the study\/studies or the approach employed for the program\/policy or evaluation; a summary of analyses, results and conclusions; and an overview of actions, recommendations, or impacts that occurred or that will be implemented or evaluated.\r\n\t<\/div>\r\n\r\n<h5>Printed Poster (85-minutes)<\/h5>\r\n   <div style=\"padding-left: 20px;\">\r\nUsing pictures and diagrams, and word\/text sparingly, printed posters are the most appropriate and efficient method for presenting empirical research. A poster title should inform one about the results of a study or studies or speak to the effectiveness or impact of a policy\/program or intervention.\r\n\r\nA submission for a printed poster should include the following information: rationale for the study\/studies or program\/policy or intervention; method of the study\/studies or the approach employed for the program\/policy; a summary of analyses or evaluations that were conducted; a summary of the results and the conclusions that follow from them; and an overview of actions, recommendations, or impacts that were made, implemented and\/or evaluated.\r\n\r\nInformation on the orientation of the posters (portrait; landscape), size of the posters, etc. will be provided upon acceptance of a submission.\r\n\t<\/div>\r\n\r\n<h5>Workshop (85 minutes):<\/h5>\r\n   <div style=\"padding-left: 20px;\">\r\nWorkshops are offered during May 28th - May 30th, 2020. Workshops are intended for the same purpose and have the same requirements as Pre-Convention Professional Development Workshops (PcPDWs). (Please note: Some workshops are eligible for CE Credits. Free access to the workshop is included with your convention registration) \r\n\r\nWorkshops are presented by an individual or a group and are intended to have a clearly defined practical, experiential, and\/or demonstrational component. Workshops are intended to be participatory events where delegates engage and interact with each other. Led by a presenter or presenters with widely acknowledged expertise and experience in the topic area, each workshop should focus on ensuring that participants leave the workshop with at least 3 tangible new skills, tools, and\/or techniques (i.e., learning outcomes). Thus, good Workshops are innovative, interactive, inclusive, integrative, developmental, provocative, logistically sound, and provide both novice and experienced psychologists with an opportunity to continue their professional development. CE Credits may be available if applicable. \r\n\r\nIn contrast to PcPDWs, a total of only 85 minutes will be allocated to each Workshop (with 75 minutes for the workshop and 10 minutes for set-up and tear-down). Please be aware that your submission may be declined if the reviewers deem that their is insufficient time to provide an adequate summary of the material described in the abstract.   \r\n\r\nThrough the 2020 CPA Convention Submission System, you will be able to access\/edit your abstracts and view the summaries. You will be able to edit your submission until the system closes at 23:59 EST December 2nd, 2019. It is your responsibility to make the changes online or to send questions about your submissions to <a href=\"mailto:convention@cpa.ca\">convention@cpa.ca<\/a> before December 2nd, 2018. The submission review phase begins on December 3rd, 2019. Submissions may not be changed during (or following) the official submission review period.\r\n<!--\r\nThe CPA\u2019s annual convention also features workshops offered during the convention itself, from May 28<sup>th<\/sup> through May 30<sup>th<\/sup>, 2020.\u00a0 Access to these workshops is free with convention registration; some workshops will be eligible for CE credits.\r\nWorkshops are intended for the same purpose and have the same requirements as Pre-Convention Professional Development Workshops (PcPDWs). Workshops are presented by an individual or a group and are intended to have a clearly defined practical, experiential, and\/or demonstrational component. Workshops are intended to be participatory events where delegates engage and interact with each other. Led by a presenter or presenters with widely acknowledged expertise and experience in the topic area, each workshop should focus on ensuring that participants leave the workshop with at least 3 tangible new skills, tools, and\/or techniques (i.e., learning outcomes). Thus, good Workshops are innovative, interactive, inclusive, integrative, developmental, provocative, logistically sound, and provide both novice and experienced psychologists with an opportunity to continue their professional development.\r\nIn contrast to PcPDWs, these workshops are allocated 85-minutes in the program (75-minutes for the workshop and 10-minutes for set-up\/tear-down).-->\r\n\t<\/div>\r\n\r\n<h5>12-Minute Talks (12-minutes)<\/h5>\r\n   <div style=\"padding-left: 20px;\">\r\nThe 12-Minute Talk format is intended for making a detailed report about a series (more than 2) of empirical studies or a complex program or intervention.\r\n\r\nEach 12-minute Talk is allocated 10-minutes for presentation and 2-minutes for questions. This format is reserved for sharing information about a complex issue, series of studies or an involved program or intervention.\r\n\r\nThe convention program can accommodate only a small number of 12-Minute Talks; thus, choose this option only if it is clearly impossible to present your work either as a printed poster or as a GIMME-5.\r\n\r\nA submission for a 12-Minute Talk should include the following information: empirical and theoretical context and rationale for the studies or program\/policy or intervention; general method of the studies or the approach employed for the program\/policy or evaluation; a summary of analyses, results and conclusions; and an overview of actions, recommendations, or impacts that occurred or that will be implemented or evaluated; and informative descriptors for grouping\/scheduling.\r\n\t<\/div>\r\n\r\n<h5>Review Session (25-minutes)<\/h5>\r\n   <div style=\"padding-left: 20px;\">\r\nReview Session are intended for the review\/synthesis of one or more theoretical perspective(s), methods or analyses. This type of submission is not for presenting new empirical research. The presenter is normally a senior expert in the area; submissions by a novice just entering the area will not be accepted.\r\n\r\nEach presentation is allocated 25-minutes; in the program, three presentations may be grouped together in a single session, with a moderator for keeping the session on schedule.\r\n\t<\/div>\r\n\r\n<h5>Symposium (55-minutes):<\/h5>\r\n   <div style=\"padding-left: 20px;\">\r\nA Symposium is a format for delivering a series of Spoken Presentations that focus on the same topic. Each symposium is expected to include a moderator\/convenor (10-minutes); overall title and abstract; and 3 papers (10-minutes each) each with an accompanying title and abstract. Symposium convenors have the option of including a Discussant.\r\n\r\nEach Symposium is created and submitted by one person, called the symposium moderator (or convenor). The moderator\/convenor can function in one of three manners: moderator\/convenor only, presenter of one of the Spoken Presentations, or symposium discussant.\r\n\r\nA submission for a symposium must include the following:\r\n<ul>\r\n \t<li>an overall abstract of the symposium with the following information: a brief description of the symposium topic; a statement of what makes this topic novel, contentious, or pertinent to the convention; and a clear statement of how each presenter will offer a unique approach\/perspective to the proposed topic.<\/li>\r\n \t<li>for each paper, an abstract that includes: empirical and theoretical context and rationale for the study or program\/policy or intervention; the general method of the study or the approach employed for the program\/policy or evaluation; a summary of the issue or analyses\/, results\/ conclusions; and an overview of actions, recommendations, or impacts that occurred or that will be implemented or evaluated.<\/li>\r\n<\/ul>\r\n<strong><em>Note:<\/em> <\/strong>The symposium moderator (or convenor) is responsible for creating an engaging and productive experience for panel members and session attendees. The moderator\/convenor should arrange at least one meeting, in person, by phone or electronically, among the panel members prior to the convention. On the day of the symposium, the moderator\/convenor is responsible for managing the allotted time (55-minutes), ensuring that the symposium both begins and ends on time, and that each panelist has an equitable share of the available time. The moderator\/convenor also ensures that at least 15 minutes of the symposium time is set aside for conversation with the session attendees.\r\n\t<\/div>\r\n<\/div>","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-6412","page","type-page","status-publish","hentry"],"aioseo_notices":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 20:11:32","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/convention.cpa.ca\/fr\/wp-json\/wp\/v2\/pages\/6412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/convention.cpa.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/convention.cpa.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/convention.cpa.ca\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/convention.cpa.ca\/fr\/wp-json\/wp\/v2\/comments?post=6412"}],"version-history":[{"count":33,"href":"https:\/\/convention.cpa.ca\/fr\/wp-json\/wp\/v2\/pages\/6412\/revisions"}],"predecessor-version":[{"id":16950,"href":"https:\/\/convention.cpa.ca\/fr\/wp-json\/wp\/v2\/pages\/6412\/revisions\/16950"}],"up":[{"embeddable":true,"href":"https:\/\/convention.cpa.ca\/fr\/wp-json\/wp\/v2\/pages\/2507"}],"wp:attachment":[{"href":"https:\/\/convention.cpa.ca\/fr\/wp-json\/wp\/v2\/media?parent=6412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}